{"id":56,"date":"2015-01-24T09:46:15","date_gmt":"2015-01-24T15:46:15","guid":{"rendered":"http:\/\/www.etn.com.mx\/blog\/?p=56"},"modified":"2017-04-20T10:00:52","modified_gmt":"2017-04-20T15:00:52","slug":"adquiere-en-oxxo-tus-boletos-de-autobus-2","status":"publish","type":"post","link":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/","title":{"rendered":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !!"},"content":{"rendered":"<h1 style=\"text-align: justify;\"><em><strong>Facilidad de compra en boletos de autob\u00fas<\/strong><\/em><\/h1>\n<p style=\"text-align: justify;\"><em><strong>ETN Turistar Lujo<\/strong><\/em> tiene un beneficio adicional para usted. Aparte de la venta de boletos en taquillas, ponemos a disposici\u00f3n su adquisici\u00f3n\u00a0en nuestros <strong>puntos de venta.<\/strong>\u00a0\u00c9stos los puede encontrar en las <strong>Ciudad de M\u00e9xico<\/strong>\u00a0y <strong>Guadalajara<\/strong> con sus respectivas \u00e1reas metropolitanas.<\/p>\n<p>Adem\u00e1s de la comodidad de no trasladarse a la central de autobuses, puede aprovechar la <strong>compra de sus boletos redondos.<\/strong>\u00a0Con posibilidad de obtener un <strong>10% de descuento<\/strong> en el boleto de regreso (<a title=\"Restricciones 10% en Taquillas\" href=\"http:\/\/www.etn.com.mx\/promociones.php\">Restricciones<\/a>)<\/p>\n<hr \/>\n<p style=\"padding-left: 30px;\"><a title=\"Puntos de Venta\" href=\"http:\/\/www.etn.com.mx\/puntosdeventa.php\"><img decoding=\"async\" class=\" wp-image-120 size-medium alignleft\" src=\"http:\/\/www.etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico-300x158.jpg\" alt=\"pv_posteo_mexico\" width=\"300\" height=\"158\" srcset=\"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico-300x158.jpg 300w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico-100x53.jpg 100w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico-150x79.jpg 150w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico-200x105.jpg 200w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico-450x236.jpg 450w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a title=\"Puntos de Venta\" href=\"http:\/\/www.etn.com.mx\/puntosdeventa.php\"><img decoding=\"async\" class=\" size-medium wp-image-126 alignright\" src=\"http:\/\/www.etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_gdl-300x158.jpg\" alt=\"pv_posteo_gdl\" width=\"300\" height=\"158\" srcset=\"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_gdl-300x158.jpg 300w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_gdl-100x53.jpg 100w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_gdl-150x79.jpg 150w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_gdl-200x105.jpg 200w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_gdl-450x236.jpg 450w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_gdl.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><b><i>consulte nuestras direcciones en<\/i><\/b><\/p>\n<h4 style=\"text-align: center;\"><a title=\"Puntos de Venta\" href=\"http:\/\/www.etn.com.mx\/puntosdeventa.php\"><em><strong>www.etn.com.mx<\/strong><\/em><\/a><\/h4>\n<p style=\"text-align: center;\">Siguenos tambien por nuestras redes sociales <a title=\"Facebook ETN TURISTAR\" href=\"https:\/\/www.facebook.com\/etnturistar?ref=hl\">Facebook<\/a>, <a title=\"Twitter ETN TURISTAR\" href=\"https:\/\/twitter.com\/ETNTURISTAR\">Twitter<\/a>, <a title=\"Google+ ETN TURISTAR\" href=\"https:\/\/plus.google.com\/u\/1\/b\/101297167117795465671\/+EtnMxTuristar\">Google+<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facilidad de compra en boletos de autob\u00fas ETN Turistar Lujo tiene un beneficio adicional para usted. Aparte de la venta de boletos en taquillas, ponemos a disposici\u00f3n su adquisici\u00f3n\u00a0en nuestros puntos de venta.\u00a0\u00c9stos los puede encontrar en las Ciudad de M\u00e9xico\u00a0y Guadalajara con sus respectivas \u00e1reas metropolitanas. Adem\u00e1s de la comodidad de no trasladarse a la central de autobuses, puede aprovechar la compra de sus boletos redondos.\u00a0Con posibilidad de obtener un 10% de descuento en el boleto de regreso (Restricciones) consulte nuestras direcciones en www.etn.com.mx Siguenos tambien por nuestras redes sociales Facebook, Twitter, Google+<\/p>\n","protected":false},"author":1,"featured_media":120,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[322,8,3],"tags":[21,805,802,20,804,803,673],"class_list":["post-56","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cdmx","category-compra-de-boletos-de-autobus","category-destinos","tag-boletos-de-autobus","tag-descuentos-en-boletos-de-autobus","tag-facilidad-de-compra-de-boletos","tag-puntos-de-venta","tag-puntos-de-venta-cdmx","tag-puntos-de-venta-guadalajara","tag-viaja-por-mexico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! - Blog ETN Turistar<\/title>\n<meta name=\"description\" content=\"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! Compra de Boletos Blog ETN Turistar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! - Blog ETN Turistar\" \/>\n<meta property=\"og:description\" content=\"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! Compra de Boletos Blog ETN Turistar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog ETN Turistar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/etnturistar\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-24T15:46:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-20T15:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ETN Turistar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ETNTURISTAR\" \/>\n<meta name=\"twitter:site\" content=\"@ETNTURISTAR\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ETN Turistar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/\"},\"author\":{\"name\":\"ETN Turistar\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/person\\\/2dd4ef2d2ed40cf1379ed17eefc34c46\"},\"headline\":\"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !!\",\"datePublished\":\"2015-01-24T15:46:15+00:00\",\"dateModified\":\"2017-04-20T15:00:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/\"},\"wordCount\":122,\"commentCount\":18,\"publisher\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pv_posteo_mexico.jpg\",\"keywords\":[\"Boletos de Autobus\",\"Descuentos en boletos de autob\u00fas\",\"Facilidad de compra de boletos\",\"Puntos de Venta\",\"Puntos de venta CDMX\",\"Puntos de venta Guadalajara\",\"Viaja por M\u00e9xico\"],\"articleSection\":[\"CDMX\",\"Compra de Boletos\",\"Destinos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/\",\"name\":\"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! - Blog ETN Turistar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pv_posteo_mexico.jpg\",\"datePublished\":\"2015-01-24T15:46:15+00:00\",\"dateModified\":\"2017-04-20T15:00:52+00:00\",\"description\":\"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! Compra de Boletos Blog ETN Turistar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pv_posteo_mexico.jpg\",\"contentUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/pv_posteo_mexico.jpg\",\"width\":600,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/adquiere-en-oxxo-tus-boletos-de-autobus-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio Blog\",\"item\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compra de Boletos\",\"item\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/category\\\/compra-de-boletos-de-autobus\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\",\"name\":\"Blog ETN\",\"description\":\"Blog ETN L\u00ednea de Autobuses de lujo con destinos a M\u00e9xico, Guadalajara, Morelia, Le\u00f3n, Quer\u00e9taro, San Luis Potos\u00ed, Monterrey, Acapulco y 24 estados de la rep\u00fablica.\",\"publisher\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\"},\"alternateName\":\"Autobuses ETN Turistar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\",\"name\":\"ETN Turistar Lujo\",\"alternateName\":\"Boletos de autobus ETN\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-etnturistar.png\",\"contentUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-etnturistar.png\",\"width\":495,\"height\":52,\"caption\":\"ETN Turistar Lujo\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/etnturistar\\\/\",\"https:\\\/\\\/x.com\\\/ETNTURISTAR\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/person\\\/2dd4ef2d2ed40cf1379ed17eefc34c46\",\"name\":\"ETN Turistar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"caption\":\"ETN Turistar\"},\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/author\\\/webmaster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! - Blog ETN Turistar","description":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! Compra de Boletos Blog ETN Turistar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! - Blog ETN Turistar","og_description":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! Compra de Boletos Blog ETN Turistar","og_url":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/","og_site_name":"Blog ETN Turistar","article_publisher":"https:\/\/www.facebook.com\/etnturistar\/","article_published_time":"2015-01-24T15:46:15+00:00","article_modified_time":"2017-04-20T15:00:52+00:00","og_image":[{"width":600,"height":315,"url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico.jpg","type":"image\/jpeg"}],"author":"ETN Turistar","twitter_card":"summary_large_image","twitter_creator":"@ETNTURISTAR","twitter_site":"@ETNTURISTAR","twitter_misc":{"Escrito por":"ETN Turistar","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#article","isPartOf":{"@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/"},"author":{"name":"ETN Turistar","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/person\/2dd4ef2d2ed40cf1379ed17eefc34c46"},"headline":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !!","datePublished":"2015-01-24T15:46:15+00:00","dateModified":"2017-04-20T15:00:52+00:00","mainEntityOfPage":{"@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/"},"wordCount":122,"commentCount":18,"publisher":{"@id":"https:\/\/etn.com.mx\/blog\/#organization"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#primaryimage"},"thumbnailUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico.jpg","keywords":["Boletos de Autobus","Descuentos en boletos de autob\u00fas","Facilidad de compra de boletos","Puntos de Venta","Puntos de venta CDMX","Puntos de venta Guadalajara","Viaja por M\u00e9xico"],"articleSection":["CDMX","Compra de Boletos","Destinos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/","url":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/","name":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! - Blog ETN Turistar","isPartOf":{"@id":"https:\/\/etn.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#primaryimage"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#primaryimage"},"thumbnailUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico.jpg","datePublished":"2015-01-24T15:46:15+00:00","dateModified":"2017-04-20T15:00:52+00:00","description":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !! Compra de Boletos Blog ETN Turistar","breadcrumb":{"@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#primaryimage","url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico.jpg","contentUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/01\/pv_posteo_mexico.jpg","width":600,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/etn.com.mx\/blog\/adquiere-en-oxxo-tus-boletos-de-autobus-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio Blog","item":"https:\/\/etn.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Compra de Boletos","item":"https:\/\/etn.com.mx\/blog\/category\/compra-de-boletos-de-autobus\/"},{"@type":"ListItem","position":3,"name":"\u00a1\u00a1 Compre sus Boletos de Autobus en nuestros puntos de Venta en la Cd. de Mexico y Guadalajara !!"}]},{"@type":"WebSite","@id":"https:\/\/etn.com.mx\/blog\/#website","url":"https:\/\/etn.com.mx\/blog\/","name":"Blog ETN","description":"Blog ETN L\u00ednea de Autobuses de lujo con destinos a M\u00e9xico, Guadalajara, Morelia, Le\u00f3n, Quer\u00e9taro, San Luis Potos\u00ed, Monterrey, Acapulco y 24 estados de la rep\u00fablica.","publisher":{"@id":"https:\/\/etn.com.mx\/blog\/#organization"},"alternateName":"Autobuses ETN Turistar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/etn.com.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/etn.com.mx\/blog\/#organization","name":"ETN Turistar Lujo","alternateName":"Boletos de autobus ETN","url":"https:\/\/etn.com.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2023\/07\/logo-etnturistar.png","contentUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2023\/07\/logo-etnturistar.png","width":495,"height":52,"caption":"ETN Turistar Lujo"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/etnturistar\/","https:\/\/x.com\/ETNTURISTAR"]},{"@type":"Person","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/person\/2dd4ef2d2ed40cf1379ed17eefc34c46","name":"ETN Turistar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","caption":"ETN Turistar"},"url":"https:\/\/etn.com.mx\/blog\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":11,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/56\/revisions"}],"predecessor-version":[{"id":2266,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/56\/revisions\/2266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/media\/120"}],"wp:attachment":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=56"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=56"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}