{"id":252,"date":"2015-02-10T18:06:40","date_gmt":"2015-02-11T00:06:40","guid":{"rendered":"http:\/\/www.etn.com.mx\/blog\/?p=252"},"modified":"2017-04-20T13:24:25","modified_gmt":"2017-04-20T18:24:25","slug":"etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo","status":"publish","type":"post","link":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/","title":{"rendered":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo"},"content":{"rendered":"<h3 style=\"text-align: center;\">#Viajeros, les compartimos algunos tips al viajar con ni\u00f1os a bordo de <strong>ETN Turistar<\/strong><\/h3>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-268 aligncenter\" src=\"http:\/\/www.etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg\" alt=\"Tips de Viaje con Ni\u00f1os Abordo\" width=\"678\" height=\"680\" srcset=\"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg 678w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12-150x150.jpg 150w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12-300x301.jpg 300w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12-100x100.jpg 100w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12-200x201.jpg 200w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12-450x451.jpg 450w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12-600x602.jpg 600w\" sizes=\"(max-width: 678px) 100vw, 678px\" \/><\/a><\/p>\n<p>1.- Carga siempre con su juguete preferido, as\u00ed\u00a0tendr\u00e1 un distractor y el viaje se har\u00e1 m\u00e1s ameno.<br \/>\n2.- Los ni\u00f1os deber\u00e1n usar siempre el cintur\u00f3n de seguridad para evitar cualquier eventualidad en el camino.<br \/>\n3.- Recuerda llevar lo necesario para atender las necesidades del peque\u00f1o tales como agua, snacks, alguna frazada ligera, pa\u00f1ales, etc.<br \/>\n4.- Consulta el clima de la ciudad a la cual vas a viajar; esto ser\u00e1 de gran utilidad al momento de saber qu\u00e9 tipo de ropa empacar.<br \/>\n5.- Contrario a lo que se podr\u00eda pensar, no es recomendable que dibujen, ya que podr\u00edan marearse. En caso de que esto suceda siempre se recomienda llevar un dulce o pastillas contra el mareo.<\/p>\n<p style=\"text-align: justify;\">Te invitamos a compartirnos tus tips cuando viajas con tus peque\u00f1os a bordo de <strong>ETN Turistar<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Recuerda en<\/p>\n<p class=\"h2-section-title\"><strong><span class=\"bold\">ETN y Turistar<\/span><\/strong> pensando en la comodidad de nuestros clientes; le ofrece el servicio de entrega de boletos a domicilio u oficina. Esto\u00a0sin costo adicional en el \u00e1rea metropolitana de la Ciudad de M\u00e9xico y Guadalajara.<\/p>\n<p class=\"h3-section-info\">Este servicio le brinda la posibilidad de pagar sus boletos con tarjeta de cr\u00e9dito, d\u00e9bito o en efectivo. As\u00ed evitar\u00e1 traslados innecesarios a la terminal de autobuses.<\/p>\n<p class=\"h3-section-info\">Solicite este servicio llamando a nuestro <strong>Contact Center<\/strong>:<\/p>\n<p class=\"center title-lugar\">Lada nacional sin costo<br \/>\n<strong><em><span class=\"bold resaltar txt25\">01 800 8000 386<\/span><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Viajeros, les compartimos algunos tips al viajar con ni\u00f1os a bordo de ETN Turistar 1.- Carga siempre con su juguete preferido, as\u00ed\u00a0tendr\u00e1 un distractor y el viaje se har\u00e1 m\u00e1s ameno. 2.- Los ni\u00f1os deber\u00e1n usar siempre el cintur\u00f3n de seguridad para evitar cualquier eventualidad en el camino. 3.- Recuerda llevar lo necesario para atender las necesidades del peque\u00f1o tales como agua, snacks, alguna frazada ligera, pa\u00f1ales, etc. 4.- Consulta el clima de la ciudad a la cual vas a viajar; esto ser\u00e1 de gran utilidad al momento de saber qu\u00e9 tipo de ropa empacar. 5.- Contrario a lo que se podr\u00eda pensar, no es recomendable que dibujen, ya que podr\u00edan marearse. En caso de que esto suceda siempre se recomienda llevar un dulce o pastillas contra el mareo. Te invitamos a compartirnos tus tips cuando viajas con tus peque\u00f1os a bordo de ETN Turistar. Recuerda en ETN y Turistar pensando en la comodidad de nuestros clientes; le ofrece el servicio de entrega de boletos a domicilio u oficina. Esto\u00a0sin costo adicional en el \u00e1rea metropolitana de la Ciudad de M\u00e9xico y Guadalajara. Este servicio le brinda la posibilidad de pagar sus boletos con tarjeta de cr\u00e9dito, d\u00e9bito o en efectivo. As\u00ed evitar\u00e1 traslados innecesarios a la terminal de autobuses. Solicite este servicio llamando a nuestro Contact Center: Lada nacional sin costo 01 800 8000 386<\/p>\n","protected":false},"author":1,"featured_media":268,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[8,3,46,45,52],"tags":[21,857,53,858],"class_list":["post-252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compra-de-boletos-de-autobus","category-destinos","category-etn-turistar","category-tips-de-viaje","category-venta-a-domicilio","tag-boletos-de-autobus","tag-tip-de-viaje","tag-venta-a-domiclio","tag-viajar-con-ninos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo - Blog ETN Turistar<\/title>\n<meta name=\"description\" content=\"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo Blog ETN Turistar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo - Blog ETN Turistar\" \/>\n<meta property=\"og:description\" content=\"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo Blog ETN Turistar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog ETN Turistar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/etnturistar\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-11T00:06:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-20T18:24:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"678\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ETN Turistar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ETNTURISTAR\" \/>\n<meta name=\"twitter:site\" content=\"@ETNTURISTAR\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ETN Turistar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/\"},\"author\":{\"name\":\"ETN Turistar\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/person\\\/2dd4ef2d2ed40cf1379ed17eefc34c46\"},\"headline\":\"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo\",\"datePublished\":\"2015-02-11T00:06:40+00:00\",\"dateModified\":\"2017-04-20T18:24:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/\"},\"wordCount\":250,\"commentCount\":77,\"publisher\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Diapositiva12.jpg\",\"keywords\":[\"Boletos de Autobus\",\"TIP de viaje\",\"Venta a Domiclio\",\"Viajar con ni\u00f1os\"],\"articleSection\":[\"Compra de Boletos\",\"Destinos\",\"ETN Turistar\",\"Tips de Viaje\",\"Venta a Domicilio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/\",\"name\":\"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo - Blog ETN Turistar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Diapositiva12.jpg\",\"datePublished\":\"2015-02-11T00:06:40+00:00\",\"dateModified\":\"2017-04-20T18:24:25+00:00\",\"description\":\"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo Blog ETN Turistar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Diapositiva12.jpg\",\"contentUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Diapositiva12.jpg\",\"width\":678,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio Blog\",\"item\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compra de Boletos\",\"item\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/category\\\/compra-de-boletos-de-autobus\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\",\"name\":\"Blog ETN\",\"description\":\"Blog ETN L\u00ednea de Autobuses de lujo con destinos a M\u00e9xico, Guadalajara, Morelia, Le\u00f3n, Quer\u00e9taro, San Luis Potos\u00ed, Monterrey, Acapulco y 24 estados de la rep\u00fablica.\",\"publisher\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\"},\"alternateName\":\"Autobuses ETN Turistar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\",\"name\":\"ETN Turistar Lujo\",\"alternateName\":\"Boletos de autobus ETN\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-etnturistar.png\",\"contentUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-etnturistar.png\",\"width\":495,\"height\":52,\"caption\":\"ETN Turistar Lujo\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/etnturistar\\\/\",\"https:\\\/\\\/x.com\\\/ETNTURISTAR\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/person\\\/2dd4ef2d2ed40cf1379ed17eefc34c46\",\"name\":\"ETN Turistar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"caption\":\"ETN Turistar\"},\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/author\\\/webmaster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo - Blog ETN Turistar","description":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo Blog ETN Turistar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/","og_locale":"es_ES","og_type":"article","og_title":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo - Blog ETN Turistar","og_description":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo Blog ETN Turistar","og_url":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/","og_site_name":"Blog ETN Turistar","article_publisher":"https:\/\/www.facebook.com\/etnturistar\/","article_published_time":"2015-02-11T00:06:40+00:00","article_modified_time":"2017-04-20T18:24:25+00:00","og_image":[{"width":678,"height":680,"url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg","type":"image\/jpeg"}],"author":"ETN Turistar","twitter_card":"summary_large_image","twitter_creator":"@ETNTURISTAR","twitter_site":"@ETNTURISTAR","twitter_misc":{"Escrito por":"ETN Turistar","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#article","isPartOf":{"@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/"},"author":{"name":"ETN Turistar","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/person\/2dd4ef2d2ed40cf1379ed17eefc34c46"},"headline":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo","datePublished":"2015-02-11T00:06:40+00:00","dateModified":"2017-04-20T18:24:25+00:00","mainEntityOfPage":{"@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/"},"wordCount":250,"commentCount":77,"publisher":{"@id":"https:\/\/etn.com.mx\/blog\/#organization"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#primaryimage"},"thumbnailUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg","keywords":["Boletos de Autobus","TIP de viaje","Venta a Domiclio","Viajar con ni\u00f1os"],"articleSection":["Compra de Boletos","Destinos","ETN Turistar","Tips de Viaje","Venta a Domicilio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/","url":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/","name":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo - Blog ETN Turistar","isPartOf":{"@id":"https:\/\/etn.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#primaryimage"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#primaryimage"},"thumbnailUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg","datePublished":"2015-02-11T00:06:40+00:00","dateModified":"2017-04-20T18:24:25+00:00","description":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo Blog ETN Turistar","breadcrumb":{"@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#primaryimage","url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg","contentUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2015\/02\/Diapositiva12.jpg","width":678,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/etn.com.mx\/blog\/etn-turistar-les-da-algunos-tips-de-viaje-con-ninos-a-bordo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio Blog","item":"https:\/\/etn.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Compra de Boletos","item":"https:\/\/etn.com.mx\/blog\/category\/compra-de-boletos-de-autobus\/"},{"@type":"ListItem","position":3,"name":"ETN Turistar les da algunos Tips de viaje, con ni\u00f1os a bordo"}]},{"@type":"WebSite","@id":"https:\/\/etn.com.mx\/blog\/#website","url":"https:\/\/etn.com.mx\/blog\/","name":"Blog ETN","description":"Blog ETN L\u00ednea de Autobuses de lujo con destinos a M\u00e9xico, Guadalajara, Morelia, Le\u00f3n, Quer\u00e9taro, San Luis Potos\u00ed, Monterrey, Acapulco y 24 estados de la rep\u00fablica.","publisher":{"@id":"https:\/\/etn.com.mx\/blog\/#organization"},"alternateName":"Autobuses ETN Turistar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/etn.com.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/etn.com.mx\/blog\/#organization","name":"ETN Turistar Lujo","alternateName":"Boletos de autobus ETN","url":"https:\/\/etn.com.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2023\/07\/logo-etnturistar.png","contentUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2023\/07\/logo-etnturistar.png","width":495,"height":52,"caption":"ETN Turistar Lujo"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/etnturistar\/","https:\/\/x.com\/ETNTURISTAR"]},{"@type":"Person","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/person\/2dd4ef2d2ed40cf1379ed17eefc34c46","name":"ETN Turistar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","caption":"ETN Turistar"},"url":"https:\/\/etn.com.mx\/blog\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=252"}],"version-history":[{"count":6,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/252\/revisions"}],"predecessor-version":[{"id":2324,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/252\/revisions\/2324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/media\/268"}],"wp:attachment":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}