{"id":2146,"date":"2017-03-01T13:09:34","date_gmt":"2017-03-01T19:09:34","guid":{"rendered":"http:\/\/etn.com.mx\/blog\/?p=2146"},"modified":"2017-03-01T13:09:34","modified_gmt":"2017-03-01T19:09:34","slug":"aldea-plop-radio","status":"publish","type":"post","link":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/","title":{"rendered":"Aldea PLOP Radio y ETN TURISTAR LUJO"},"content":{"rendered":"<h2 style=\"text-align: center\"><span style=\"color: #0000ff\">ETN TURISTAR LUJO te invita a Aldea PLOP Radio\u00a0<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>\u00bfQu\u00e9 es ALDEA PLOP Radio?<\/p>\n<p>En una \u00e9poca en la que la oferta de festivales abunda y la renacida llama de los gigs underground est\u00e1 m\u00e1s fuerte que nunca, por ac\u00e1 en PLOP Radio decidimos que para iniciar el 2017 y prepararlos para todas las cosas buenas que vienen, era necesario iniciar con un pre\u00e1mbulo; una especie de peque\u00f1o evento con el que pudi\u00e9ramos darle la bienvenida al 2017.<\/p>\n<p><a href=\"http:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2147 size-full\" title=\"aldea plop radio\" src=\"http:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea1.jpg\" width=\"1200\" height=\"630\" srcset=\"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea1.jpg 1200w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea1-300x158.jpg 300w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea1-768x403.jpg 768w, https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea1-1024x538.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>Por eso mismo se creo el concepto de ALDEA, un picnic de m\u00fasica alternativa que invitara a talentos nacionales e internacionales, haciendo \u00e9nfasis en nombres latinoamericanos. Una de las caracter\u00edsticas del evento es que es familiar y no se permite la venta o entrada de alcohol, esto para tener un ambiente sano y sin riesgos.<\/p>\n<p>ALDEA decide tumbar murallas, incluir tanto a nombres locales como Americanos y Mexicanos que viven en EEUU y siguen formando parte del escenario nacional.<\/p>\n<p>Con la participaci\u00f3n de Chile, Venezuela, Costa Rica, EEUU y por supuesto, M\u00e9xico, ALDEA abre sus puertas para celebrar una primera edici\u00f3n en el Deportivo Lomas Altas este pr\u00f3ximo 04 de marzo.<\/p>\n<p>Seras libre de llevar tu propia comida as\u00ed como balones, frisbee, pelotas, cuerda de saltar, etc. De igual forma si no llevas comida habr\u00e1 venta de bebidas sin alcohol y Food Trucks.<\/p>\n<p>Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla.<\/p>\n<p>DEPORTIVO LOMAS ALTAS, ESTADO MAYOR PRESIDENCIAL<\/p>\n<p>S\u00c1BADO 4 DE MARZO DE 13:00 A 23:30<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ETN TURISTAR LUJO te invita a Aldea PLOP Radio\u00a0 &nbsp; \u00bfQu\u00e9 es ALDEA PLOP Radio? En una \u00e9poca en la que la oferta de festivales abunda y la renacida llama de los gigs underground est\u00e1 m\u00e1s fuerte que nunca, por ac\u00e1 en PLOP Radio decidimos que para iniciar el 2017 y prepararlos para todas las cosas buenas que vienen, era necesario iniciar con un pre\u00e1mbulo; una especie de peque\u00f1o evento con el que pudi\u00e9ramos darle la bienvenida al 2017. Por eso mismo se creo el concepto de ALDEA, un picnic de m\u00fasica alternativa que invitara a talentos nacionales e internacionales, haciendo \u00e9nfasis en nombres latinoamericanos. Una de las caracter\u00edsticas del evento es que es familiar y no se permite la venta o entrada de alcohol, esto para tener un ambiente sano y sin riesgos. ALDEA decide tumbar murallas, incluir tanto a nombres locales como Americanos y Mexicanos que viven en EEUU y siguen formando parte del escenario nacional. Con la participaci\u00f3n de Chile, Venezuela, Costa Rica, EEUU y por supuesto, M\u00e9xico, ALDEA abre sus puertas para celebrar una primera edici\u00f3n en el Deportivo Lomas Altas este pr\u00f3ximo 04 de marzo. Seras libre de llevar tu propia comida as\u00ed como balones, frisbee, pelotas, cuerda de saltar, etc. De igual forma si no llevas comida habr\u00e1 venta de bebidas sin alcohol y Food Trucks. Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla. DEPORTIVO LOMAS ALTAS, ESTADO MAYOR PRESIDENCIAL S\u00c1BADO 4 DE MARZO DE 13:00 A 23:30<\/p>\n","protected":false},"author":1,"featured_media":2148,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[322,468],"tags":[587,586,59,21,410,297,409,494,37,48,588,13,477,19,484,11,589,590],"class_list":["post-2146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cdmx","category-468","tag-alde-plop-radio","tag-aldea","tag-autobuses","tag-boletos-de-autobus","tag-boletos-de-camion","tag-boletos-etn","tag-camiones","tag-camiones-etn","tag-compra-de-boletos","tag-descuentos","tag-estado-mayor","tag-etn","tag-etn-horarios-y-salidas","tag-etn-turistar-lujo","tag-etn-com-mx","tag-musica","tag-picnic","tag-primavera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aldea PLOP Radio y ETN TURISTAR LUJO - Blog ETN Turistar<\/title>\n<meta name=\"description\" content=\"Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aldea PLOP Radio y ETN TURISTAR LUJO - Blog ETN Turistar\" \/>\n<meta property=\"og:description\" content=\"Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog ETN Turistar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/etnturistar\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-01T19:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ETN Turistar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ETNTURISTAR\" \/>\n<meta name=\"twitter:site\" content=\"@ETNTURISTAR\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ETN Turistar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/\"},\"author\":{\"name\":\"ETN Turistar\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/person\\\/2dd4ef2d2ed40cf1379ed17eefc34c46\"},\"headline\":\"Aldea PLOP Radio y ETN TURISTAR LUJO\",\"datePublished\":\"2017-03-01T19:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/aldea2.jpg\",\"keywords\":[\"alde plop radio\",\"aldea\",\"Autobuses\",\"Boletos de Autobus\",\"boletos de camion\",\"boletos etn\",\"camiones\",\"camiones etn\",\"Compra de Boletos\",\"Descuentos\",\"estado mayor\",\"ETN\",\"etn horarios y salidas\",\"ETN Turistar Lujo\",\"etn.com.mx\",\"M\u00fasica\",\"picnic\",\"primavera\"],\"articleSection\":[\"CDMX\",\"Descuento 10+10 ETN Turistar Lujo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/\",\"name\":\"Aldea PLOP Radio y ETN TURISTAR LUJO - Blog ETN Turistar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/aldea2.jpg\",\"datePublished\":\"2017-03-01T19:09:34+00:00\",\"description\":\"Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/aldea2.jpg\",\"contentUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/aldea2.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/aldea-plop-radio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio Blog\",\"item\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descuento 10+10 ETN Turistar Lujo\",\"item\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/category\\\/1010\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aldea PLOP Radio y ETN TURISTAR LUJO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\",\"name\":\"Blog ETN\",\"description\":\"Blog ETN L\u00ednea de Autobuses de lujo con destinos a M\u00e9xico, Guadalajara, Morelia, Le\u00f3n, Quer\u00e9taro, San Luis Potos\u00ed, Monterrey, Acapulco y 24 estados de la rep\u00fablica.\",\"publisher\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\"},\"alternateName\":\"Autobuses ETN Turistar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#organization\",\"name\":\"ETN Turistar Lujo\",\"alternateName\":\"Boletos de autobus ETN\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-etnturistar.png\",\"contentUrl\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-etnturistar.png\",\"width\":495,\"height\":52,\"caption\":\"ETN Turistar Lujo\"},\"image\":{\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/etnturistar\\\/\",\"https:\\\/\\\/x.com\\\/ETNTURISTAR\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/#\\\/schema\\\/person\\\/2dd4ef2d2ed40cf1379ed17eefc34c46\",\"name\":\"ETN Turistar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g\",\"caption\":\"ETN Turistar\"},\"url\":\"https:\\\/\\\/etn.com.mx\\\/blog\\\/author\\\/webmaster\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aldea PLOP Radio y ETN TURISTAR LUJO - Blog ETN Turistar","description":"Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/","og_locale":"es_ES","og_type":"article","og_title":"Aldea PLOP Radio y ETN TURISTAR LUJO - Blog ETN Turistar","og_description":"Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla.","og_url":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/","og_site_name":"Blog ETN Turistar","article_publisher":"https:\/\/www.facebook.com\/etnturistar\/","article_published_time":"2017-03-01T19:09:34+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea2.jpg","type":"image\/jpeg"}],"author":"ETN Turistar","twitter_card":"summary_large_image","twitter_creator":"@ETNTURISTAR","twitter_site":"@ETNTURISTAR","twitter_misc":{"Escrito por":"ETN Turistar","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#article","isPartOf":{"@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/"},"author":{"name":"ETN Turistar","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/person\/2dd4ef2d2ed40cf1379ed17eefc34c46"},"headline":"Aldea PLOP Radio y ETN TURISTAR LUJO","datePublished":"2017-03-01T19:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/etn.com.mx\/blog\/#organization"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#primaryimage"},"thumbnailUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea2.jpg","keywords":["alde plop radio","aldea","Autobuses","Boletos de Autobus","boletos de camion","boletos etn","camiones","camiones etn","Compra de Boletos","Descuentos","estado mayor","ETN","etn horarios y salidas","ETN Turistar Lujo","etn.com.mx","M\u00fasica","picnic","primavera"],"articleSection":["CDMX","Descuento 10+10 ETN Turistar Lujo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/","url":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/","name":"Aldea PLOP Radio y ETN TURISTAR LUJO - Blog ETN Turistar","isPartOf":{"@id":"https:\/\/etn.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#primaryimage"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#primaryimage"},"thumbnailUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea2.jpg","datePublished":"2017-03-01T19:09:34+00:00","description":"Una de las ventajas de viajar en ETN TURISTAR LUJO es que al presentar tu boleto de autob\u00fas se te cobrara $ 50 pesos menos de tu entrada en taquilla.","breadcrumb":{"@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#primaryimage","url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea2.jpg","contentUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2017\/03\/aldea2.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/etn.com.mx\/blog\/aldea-plop-radio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio Blog","item":"https:\/\/etn.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Descuento 10+10 ETN Turistar Lujo","item":"https:\/\/etn.com.mx\/blog\/category\/1010\/"},{"@type":"ListItem","position":3,"name":"Aldea PLOP Radio y ETN TURISTAR LUJO"}]},{"@type":"WebSite","@id":"https:\/\/etn.com.mx\/blog\/#website","url":"https:\/\/etn.com.mx\/blog\/","name":"Blog ETN","description":"Blog ETN L\u00ednea de Autobuses de lujo con destinos a M\u00e9xico, Guadalajara, Morelia, Le\u00f3n, Quer\u00e9taro, San Luis Potos\u00ed, Monterrey, Acapulco y 24 estados de la rep\u00fablica.","publisher":{"@id":"https:\/\/etn.com.mx\/blog\/#organization"},"alternateName":"Autobuses ETN Turistar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/etn.com.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/etn.com.mx\/blog\/#organization","name":"ETN Turistar Lujo","alternateName":"Boletos de autobus ETN","url":"https:\/\/etn.com.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2023\/07\/logo-etnturistar.png","contentUrl":"https:\/\/etn.com.mx\/blog\/wp-content\/uploads\/2023\/07\/logo-etnturistar.png","width":495,"height":52,"caption":"ETN Turistar Lujo"},"image":{"@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/etnturistar\/","https:\/\/x.com\/ETNTURISTAR"]},{"@type":"Person","@id":"https:\/\/etn.com.mx\/blog\/#\/schema\/person\/2dd4ef2d2ed40cf1379ed17eefc34c46","name":"ETN Turistar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d28cf80567344d817834c5fde3f70d38bd14ccbb70ee9d2980029e2d6c5bb051?s=96&d=mm&r=g","caption":"ETN Turistar"},"url":"https:\/\/etn.com.mx\/blog\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/2146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=2146"}],"version-history":[{"count":1,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/2146\/revisions"}],"predecessor-version":[{"id":2149,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/posts\/2146\/revisions\/2149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/media\/2148"}],"wp:attachment":[{"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=2146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=2146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/etn.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=2146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}